{"id":6870,"date":"2026-04-13T08:54:15","date_gmt":"2026-04-13T06:54:15","guid":{"rendered":"https:\/\/sailing-amira.de\/?p=6870"},"modified":"2026-07-16T09:05:48","modified_gmt":"2026-07-16T07:05:48","slug":"tulum-ii-maya-ruinen-am-meer","status":"publish","type":"post","link":"https:\/\/sailing-amira.de\/es\/tulum-ii-maya-ruinen-am-meer\/","title":{"rendered":"Tulum II: Maya-Ruinen am Meer"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\" style=\"margin-top:0px;margin-bottom:10px\">Tulum II: Maya-Ruinen am Meer<\/h1>\n\n\n\n<p class=\"has-ast-global-color-3-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"margin-top:8px;margin-bottom:20px;font-size:18px\">Wir besichtigen die einzige Stadt der Maya, die am Meer liegt<\/p>\n\n\n\n<p class=\"has-ast-global-color-0-color has-text-color has-link-color has-small-font-size wp-elements-2 wp-block-paragraph\">Von Renate R\u00fcger, 13. April 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mexiko<\/strong> \u2013K\u00f6nigsblauer Himmel, graue Steinruinen, gr\u00fcner Dschungel und t\u00fcrkisfarbenes Meer: Mit diesem Postkarten-Bild im Kopf blicken wir auf das \u201eSchloss\u201c (El Castillo) auf einer Klippe rund zw\u00f6lf Meter \u00fcber dem Meer. Der Himmel ist bew\u00f6lkt, eher grau, das Meer ist tr\u00fcb, eher ockerbraun statt kr\u00e4ftig-t\u00fcrkis und Menschen, die sich an diesem Strand vergn\u00fcgen, gibt es auch nicht, stattdessen \u2013 wenn auch nicht viel \u2013 Sargassum. Und trotz alledem ist der Blick auf diese Ruine spektakul\u00e4r.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1800\" height=\"1012\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6.jpg\" alt=\"Blick auf \u201eEl Castillo\u201c vom Land aus gesehen. Der Tempel steht auf einer Klippe rund zw\u00f6lf Meter \u00fcber dem Meer\" class=\"wp-image-6901\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira6-1320x742.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption class=\"wp-element-caption\">Blick auf \u201eEl Castillo\u201c vom Land aus gesehen. Der Tempel steht auf einer Klippe rund zw\u00f6lf Meter \u00fcber dem Meer (siehe gro\u00dfes Foto \u00fcber dem Text).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Das \u201eSchloss\u201c ist eigentlich ein Tempel. Die Spanier, die 1518 in Tulum landeten, gaben ihm diesen Namen, weil er sie an eine Befestigungsanlage erinnerte. Dieser Tempel ist das gr\u00f6\u00dfte Geb\u00e4ude der ehemaligen Maya-Stadt in Tulum, die einst ein wichtiges Handelszentrum war. Es ist die einzige Maya-Stadt am Meer und die einzige, die von drei Seiten von einer Mauer umgeben ist. Nur die Seite zum Meer ist frei, ist sie doch durch die Klippe vor Angreifern gesch\u00fctzt. Im Gegensatz zum nahe gelegenen Chich\u00e9n Itz\u00e1 oder Tikal in Guatemala ist Tulum, das die Maya wahrscheinlich Zam\u00e1 (Ort der Morgend\u00e4mmerung) nannten, relativ jung. Es entstand in der Sp\u00e4tphase der Maya ab 1200 nach Christus, zu einer Zeit, als andere Zentren dieser Hochkultur bereits im Niedergang waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir blicken auf die zwei kleinen Fenster im Tempel \u201eSchloss\u201c, der m\u00f6glicherweise auch als \u201eLeuchtturm\u201c diente. Wer im Boot vom Meer kommt, sollte darauf achten, dass beide Fenster exakt \u00fcbereinander stehen, dann komme er sicher durchs Korallenriff, h\u00f6ren wir. Spanische Eroberer berichten in ihren Chroniken von einem Licht, das Tag und Nacht im Tempel brannte. Haben die Maya Fackeln in die Fenster\u00f6ffnungen gestellt, um eine \u201eLeuchtlinie\u201c zur Orientierung f\u00fcr die Seefahrer zu bilden? Einen Beweis daf\u00fcr gibt es nicht. Sicher ist hingegen die religi\u00f6se Funktion dieses Geb\u00e4udes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1.jpg\"><img decoding=\"async\" width=\"1800\" height=\"1013\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1.jpg\" alt=\"Maya-Ruinen in Tulum: Tempel des herabsteigenden Gottes\" class=\"wp-image-6907\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_herabsteigenden_Gottes1-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption class=\"wp-element-caption\">Der Tempel des herabsteigenden Gottes<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Zwischen 500 und 1500 Menschen sollen innerhalb der Stadtmauern gelebt haben: die Elite, zu der Priester, H\u00e4ndler und Verwaltung z\u00e4hlten. Die Reste ihrer Steinbauten sehen wir. Die eigentliche Gr\u00f6\u00dfe der Stadt, die einst ein wichtiges Handelszentrum war, k\u00f6nnen wir nicht erkennen: Zwischen 3000 und 6000 Menschen lebten au\u00dferhalb der Mauern, sprich: die einfachen Leute wie Handwerker und Fischer, deren H\u00e4user aus Holz, Palmbl\u00e4ttern und Lehm gebaut waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass die Sonne die grauen Ruinen heute nicht ins magische Licht von Blau- und Gr\u00fcnt\u00f6nen taucht, ist f\u00fcr unsere Sinne und die Fotos schade. Aber es hat auch einen Vorteil: Es ist nicht so hei\u00df, die Besichtigung der 6,8 Hektar gro\u00dfen Anlage ist angenehm und gem\u00fctlich selbst um die Mittagszeit.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38.jpg\"><img decoding=\"async\" width=\"1800\" height=\"1013\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38.jpg\" alt=\"Blick von den Maya-Ruinen aufs Meer: Boote im Wasser, auf Sand und auf Sargassum\" class=\"wp-image-6908\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira38-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><figcaption class=\"wp-element-caption\">Boote im Meer, auf Sand am Strand und auf Sargassum<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-container-core-gallery-is-layout-7f8804c7 wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1012\" data-id=\"8093\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3.jpg\" alt=\"Maya-Ruinen in Tulum: Zwei-S\u00e4ulen-Tempel\" class=\"wp-image-8093\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Zwei-Saeulen-Tempel3-1320x742.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8064\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1.jpg\" alt=\"Maya-Ruinen in Tulum: Tempel des Windgottes\" class=\"wp-image-8064\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tempel_des_Windgottes3-1-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1012\" data-id=\"8073\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2.jpg\" alt=\"Maya-Ruinen in Tulum: Casa del Halach Uinic\" class=\"wp-image-8073\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen2-1320x742.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8070\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1.jpg\" alt=\"Maya-Ruinen: Casa del Halach Uinic in Tulum\" class=\"wp-image-8070\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Casa-del-Halach-Uinic-Tulum-Ruinen1-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8062\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7.jpg\" alt=\"Maya-Ruinen in Tulum: El Castillo\" class=\"wp-image-8062\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira7-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8078\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4.jpg\" alt=\"Maya-Ruinen in Tulum: Freskentempel\" class=\"wp-image-8078\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira4-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1012\" data-id=\"8066\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3.jpg\" alt=\"Maya-Ruinen in Tulum: Freskentempel\" class=\"wp-image-8066\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira3-1320x742.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8067\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2.jpg\" alt=\"Maya-Ruinen in Tulum: Echse lukt aus \u00d6ffnung des Freskentempels\" class=\"wp-image-8067\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira2-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8074\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4.jpg\" alt=\"Maya-Ruinen in Tulum: El Castillo\" class=\"wp-image-8074\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/El-Castillo-Tulum-Ruinen-Sailing-Amira4-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8079\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1.jpg\" alt=\"Maya-Ruinen in Tulum\" class=\"wp-image-8079\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira1-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8084\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12.jpg\" alt=\"Leguan in den Maya-Ruinen Tulum\" class=\"wp-image-8084\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira12-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8080\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2.jpg\" alt=\"Maya-Ruinen in Tulum\" class=\"wp-image-8080\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira2-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8076\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6.jpg\" alt=\"Maya-Ruinen in Tulum\" class=\"wp-image-8076\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira6-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8082\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7.jpg\" alt=\"Ein F\u00fchrer erkl\u00e4rt die Maya-Ruinen in Tulum\" class=\"wp-image-8082\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira7-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1012\" data-id=\"8065\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1.jpg\" alt=\"Deatil Maya-Ruinen in Tulum\" class=\"wp-image-8065\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Treskentempel-Tulum-Ruinen-Sailing-Amira1-1320x742.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8086\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16.jpg\" alt=\"Blick aufs Meer von den Maya-Ruinen in Tulum aus\" class=\"wp-image-8086\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira16-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8088\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1.jpg\" alt=\"Maya-Ruinen in Tulum: Dorothee will nachvollziehen, wie das &quot;Schloss&quot; als Leuchtturm diente\" class=\"wp-image-8088\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira28-1-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1012\" data-id=\"8090\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31.jpg\" alt=\"Maya-Ruinen in Tulum: Blick aufs Meer\" class=\"wp-image-8090\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira31-1320x742.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8085\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15.jpg\" alt=\"Leguan in den Maya-Ruinen von Tulum\" class=\"wp-image-8085\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira15-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"1013\" data-id=\"8091\" src=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32.jpg\" alt=\"Blick aufs Meer vin den Maya-Ruinen in Tulum aus\" class=\"wp-image-8091\" srcset=\"https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32.jpg 1800w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32-300x169.jpg 300w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32-768x432.jpg 768w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32-1536x864.jpg 1536w, https:\/\/sailing-amira.de\/wp-content\/uploads\/2026\/04\/Tulum-Maya-Ruinen-Sailing-Amira32-1320x743.jpg 1320w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mexiko \u2013 Wir besichtigen die Maya-Stadt Tulum, die  einst ein wichtiges Handelszentrum war. Es ist die einzige Stadt der Maya am Meer und die einzige, die von drei Seiten von einer Mauer umgeben ist. <\/p>\n","protected":false},"author":2,"featured_media":6898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[97,130],"tags":[158,107,159,144],"class_list":["post-6870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karibik","category-reiseberichte","tag-maya","tag-mexiko","tag-ruinen","tag-tulum"],"wp-worthy-pixel":{"ignored":false,"public":"df2d6ad5f06a456ba83f96f72477de88","server":"vg04.met.vgwort.de","url":"https:\/\/vg04.met.vgwort.de\/na\/df2d6ad5f06a456ba83f96f72477de88"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/posts\/6870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/comments?post=6870"}],"version-history":[{"count":25,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/posts\/6870\/revisions"}],"predecessor-version":[{"id":8249,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/posts\/6870\/revisions\/8249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/media\/6898"}],"wp:attachment":[{"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/media?parent=6870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/categories?post=6870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sailing-amira.de\/es\/wp-json\/wp\/v2\/tags?post=6870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}